{"id":80384,"date":"2020-03-20T08:00:00","date_gmt":"2020-03-20T08:00:00","guid":{"rendered":"https:\/\/www.viscountcruises.com\/?p=80384"},"modified":"2021-04-28T00:20:04","modified_gmt":"2021-04-27T23:20:04","slug":"easter-holidays-2020","status":"publish","type":"post","link":"https:\/\/www.viscountcruises.com\/de\/news\/2020\/03\/20\/easter-holidays-2020\/","title":{"rendered":"Easter Holidays 2020"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"80384\" class=\"elementor elementor-80384\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60fc98af elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"60fc98af\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11fd446a\" data-id=\"11fd446a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82949cf elementor-widget elementor-widget-menu-anchor\" data-id=\"82949cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"top\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d00cc86 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"d00cc86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\"><strong><u>Please Note<\/u>: Events listed on this page are unlikely to take place due to recent Government Advice on COVID-19 (Coronavirus).<\/strong><\/span>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t<button type=\"button\" class=\"elementor-alert-dismiss\" aria-label=\"Dismiss this alert.\">\n\t\t\t\t\t\t\t\t\t<span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t<\/button>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-705b19de elementor-hidden-phone elementor-widget elementor-widget-global elementor-global-21297 elementor-widget-image-carousel\" data-id=\"705b19de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.co.uk\/wp-content\/uploads\/2018\/05\/header-westminster.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-new-palace-of-westminster-houses-of-parliament-01-pcci71beluu2gvj76d4v2bzcsn2wyhnesgz7p9ibu8.jpg\" alt=\"New Palace of Westminster (Houses of Parliament)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-london-eye-01-pcfetn6z2x1c86bpu02a5cbvwny8mptkzg5lt2q06o.jpg\" alt=\"London Eye, Waterloo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-tower-bridge-01-nomqr62h453se1f2utrkmwsu3f9rwy24220hmroyuo.jpg\" alt=\"Tower Bridge\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-tower-of-london-01-nomrfj1w8kgba817luuhr9hwbx78ejroemoidxknlc.jpg\" alt=\"The Tower of London\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-thames-flood-barrier-01-pcfeq58ln48x0feo9hm9v844b171z9xju4qjhzwrcg.jpg\" alt=\"Thames Flood Barrier\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-tate-gallery-modern-art-01-pcfe658880v9z4gj1ue1t9t19vrw74j5r50lw1kbqo.jpg\" alt=\"Tate Gallery of Modern Art, Bankside\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.co.uk\/wp-content\/uploads\/2018\/04\/header-greenwich-old-royal-naval-college-01.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-county-hall-01-np085jmkug7jhkwtrq01yt9qdcak854ew6u7nc9egg.jpg\" alt=\"County Hall\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.co.uk\/wp-content\/uploads\/2018\/04\/header-stamford-wharf-oxo-tower-01.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-royal-observatory-01-pcfe6whjq7wlbtcxmo68bkxei21jecjdivxot2fwq8.jpg\" alt=\"Royal Observatory, Greenwich\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-o2-01-pcfejglx1j3ig947alls4wu48e538re9l1q8n5tjlc.jpg\" alt=\"The O2, Greenwich Peninsula, Royal Borough of Greenwich\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-london-bridge-01-pcfeps2uzfqwhvxsebxhwbfnzmzwzihb4blqs4g9rk.jpg\" alt=\"London Bridge\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-north-greenwich-01-noocdotanuyu3y2841sk5wvc2s814erflza4sls48g.jpg\" alt=\"North Greenwich Cable Car, Royal Borough of Greenwich\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-cleopatras-needle-pcci7skq41vdtkflr6x1kn3q0tck5pnmk7wamadwts.jpg\" alt=\"Cleopatras Needle\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-millennium-bridge-01-pcci2mgoiuslyrxxxygwuy2geitvtn4rumq5li1v1s.jpg\" alt=\"Millennium Bridge\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-savoy-hotel-01-nonqeri7yg90w2xak61s3i0diulc92udj9hreqhrw0.jpg\" alt=\"Savoy Hotel &amp; Savoy Theatre\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-hqs-wellington-01-nonqepmjks6g8v00v58iyihgc2ultomwv06sg6kk8g.jpg\" alt=\"HQS Wellington\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-somerset-house-01-nonqesg25aab7ovxeogenzru48gpgry3ve58w0gdps.jpg\" alt=\"Somerset House\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-royal-festival-hall-01-nqxyjk63ktf87pm1zvy6aqtq2c9y6ep4i17plft3e8.jpg\" alt=\"Royal Festival Hall, Southbank Centre\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/header-royal-national-theatre-01-pcci7hanu1fxy8vzl21iqpy6w6w5lceuio2guyumwg.jpg\" alt=\"Royal National Theatre\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d5abf28 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-global elementor-global-21300 elementor-widget-image-carousel\" data-id=\"6d5abf28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/01\/westminster-kings-reach-01.jpg\" alt=\"Kings Reach, City of Westminster\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/01\/westminster-palace-of-westminster-01.jpg\" alt=\"New Palace of Westminster (Houses of Parliament), City of Westminster | Viscount Cruises\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/london-eye-01.jpg\" alt=\"London Eye, Waterloo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/tower-bridge-01.jpg\" alt=\"Tower Bridge\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/10\/tower-of-london-01.jpg\" alt=\"Tower of London\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/02\/thames-barrier-01.jpg\" alt=\"Thames Flood Barrier, Woolwich\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/tate-modern-the-shard-01.jpg\" alt=\"Tate Modern &amp; The Shard\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/01\/royal-greenwich-old-royal-naval-college-01.jpg\" alt=\"Old Royal Naval College, Royal Borough of Greenwich\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/county-hall-01.jpg\" alt=\"County Hall\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/stamford-wharf-oxo-tower-01.jpg\" alt=\"Stamford Wharf (OXO Tower Wharf)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/05\/royal-observatory-01.jpg\" alt=\"Royal Observatory\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/01\/north-greenwich-03.jpg\" alt=\"The O2, Greenwich Peninsula, Royal Borough of Greenwich\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/london-bridge-01.jpg\" alt=\"London Bridge\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/01\/north-greenwich-02.jpg\" alt=\"North Greenwich Cable Car, Royal Borough of Greenwich\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/cleopatras-needle-01.jpg\" alt=\"Cleopatras Needle\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/millennium-bridge-01.jpg\" alt=\"Millennium Bridge, Bankside\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/05\/savoy-hotel-01.jpg\" alt=\"Savoy Hotel\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/05\/hqs-wellington-01.jpg\" alt=\"HQS Wellington\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/05\/somerset-house-01.jpg\" alt=\"Somerset House\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/04\/royal-festival-hall-01.jpg\" alt=\"Royal Festival Hall, Southbank Centre\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 von 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/05\/royal-national-theatre-01.jpg\" alt=\"Royal National Theatre\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c851bbe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c851bbe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0b8ac8\" data-id=\"c0b8ac8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c6b9fff elementor-widget elementor-widget-heading\" data-id=\"1c6b9fff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Easter Holidays 2020<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f17789f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f17789f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4660235\" data-id=\"4660235\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-263e0f88 elementor-widget elementor-widget-text-editor\" data-id=\"263e0f88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We cruise to six different piers on the River Thames linking some of London&#8217;s most popular attractions. There&#8217;s a wide range of family events taking place this Easter from Easter Egg hunts at the Old Royal Naval College to family workshops at the Cutty Sark &amp; the British Museum.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p>Our cruises to the Thames Barrier also start on the 30th March 2020 &amp; continue until the end of October. A cruise to the Thames Barrier is a great extension to your river cruise &amp; passes round the O2, beneath the North Greenwich Cable Car &amp; through the Thames Barrier before cruising back upriver.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a9ee31 elementor-widget elementor-widget-spacer\" data-id=\"9a9ee31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbce53b elementor-widget elementor-widget-heading\" data-id=\"cbce53b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What's on during the Easter Holidays?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-31562b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31562b3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d860605\" data-id=\"d860605\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fe98a56 elementor-widget elementor-widget-heading\" data-id=\"3fe98a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Categories<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e9fa0a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9fa0a8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6be8d84\" data-id=\"6be8d84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-413142c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"413142c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#familyactivities\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Family Activities<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#rivercruises\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>River Cruises<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48906c7\" data-id=\"48906c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-377ec85 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"377ec85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#artexhibitions\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Art &amp; Exhibitions<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-47f3a9d2 elementor-widget elementor-widget-spacer\" data-id=\"47f3a9d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef5bfc2 elementor-widget elementor-widget-menu-anchor\" data-id=\"ef5bfc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"familyactivities\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d44bbe3 elementor-widget elementor-widget-heading\" data-id=\"d44bbe3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Family Activities<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c98fa elementor-widget elementor-widget-menu-anchor\" data-id=\"b5c98fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"toweroflondon\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-641129f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"641129f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9da7915\" data-id=\"9da7915\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5906c85 elementor-widget elementor-widget-heading\" data-id=\"5906c85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Stop Colonel Blood from Stealing the Crown Jewel<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c32c82e elementor-widget elementor-widget-heading\" data-id=\"c32c82e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> Tower of London<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7091c4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7091c4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-974e087\" data-id=\"974e087\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cff9065 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"cff9065\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-tower-of-london-01-pcag3dgqdb4fmit4v8khmnrge752tm7ptigdhl8qsw.jpg\" title=\"Tower of London\" alt=\"Tower of London\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b915e elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"a8b915e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tower of London<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-180042f elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"180042f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-tower-of-london-01-pcag3dgqdb4fmit4v8khmnrge752tm7ptigdhl8qsw.jpg\" title=\"Tower of London\" alt=\"Tower of London\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-099d037 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"099d037\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tower of London<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fe8597d\" data-id=\"fe8597d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd469a1 elementor-widget elementor-widget-heading\" data-id=\"dd469a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About the Tower of London<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-284e0cc elementor-widget elementor-widget-global elementor-global-17643 elementor-widget-text-editor\" data-id=\"284e0cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Tower of London takes its name from the White Tower which was constructed in around 1078 by William the Conqueror. Over the last 900 years the Tower of London has served a number of uses including a fortress, armoury, royal palace, royal mint, treasury, menagerie, prison &amp; more recently the home to the crown jewels. The Tower is guarded by the Yeoman Warders who were formed by King Henry VII in 1485.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-228bf8f elementor-widget elementor-widget-spacer\" data-id=\"228bf8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e05753 elementor-widget elementor-widget-heading\" data-id=\"0e05753\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">What's On This Easter<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57ce79a elementor-widget elementor-widget-text-editor\" data-id=\"57ce79a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Crown Jewels (officially name: <em>The Crown\u00a0<\/em><i>Regalia<\/i>) have fascinated the public since they were first displayed in 1669 however in 1671 Colonel Thomas Blood attempted to steal the jewels from the Tower of London.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p>Travel back in time to 1671 &amp; join an interactive story telling of Colonel Blood&#8217;s attempt to steal the Crown Jewels. Expect hands on activities &amp; immersive story telling in Historic Royal Palaces latest Family Trail at the Tower of London.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.viscountcruises.com\/landmarks\/tower-of-london\/#thecrownregalia\" target=\"_blank\" rel=\"noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Read More about The Crown Regalia<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31e8b6d elementor-widget elementor-widget-spacer\" data-id=\"31e8b6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c56c95d elementor-widget elementor-widget-heading\" data-id=\"c56c95d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Easter Events<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05dffd5 elementor-widget elementor-widget-text-editor\" data-id=\"05dffd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Colonel Blood &amp; The Crown Jewels |<\/strong> 4th April 2020 &#8211; 21st June 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Robbery At The Tower |<\/strong> 4th April 2020 &#8211; 19th April 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f2dc385 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2dc385\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-33932b3\" data-id=\"33932b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d14afa2 elementor-widget elementor-widget-text-editor\" data-id=\"d14afa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/> \u00a0<a href=\"https:\/\/goo.gl\/maps\/Bpmt9Xbbm996x2fy9\" target=\"_blank\" rel=\"nofollow noopener\">6 Min \/ 0.5 Miles from St. Katharine Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.hrp.org.uk\/tower-of-london\/\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit Historic Royal Palaces Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-840c9bb elementor-widget elementor-widget-spacer\" data-id=\"840c9bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86f7131 elementor-widget elementor-widget-menu-anchor\" data-id=\"86f7131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"oldroyalnavalcollege\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7941898 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7941898\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0fe45dc\" data-id=\"0fe45dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad3bb19 elementor-widget elementor-widget-heading\" data-id=\"ad3bb19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hunt for Eggs at the Old Royal Naval College<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8a6dcd elementor-widget elementor-widget-heading\" data-id=\"a8a6dcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> Old Royal Naval College<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f8a7330 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8a7330\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72da67b\" data-id=\"72da67b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f28eb4f elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"f28eb4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-old-royal-naval-college-01-pcag39pdlyzac2ylh6xzcopm0nnlytssgzufkhebhs.jpg\" title=\"Old Royal Naval College, Royal Borough of Greenwich\" alt=\"Old Royal Naval College, Royal Borough of Greenwich\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a8d2bb elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"5a8d2bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Old Royal Naval College<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b44a76 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"1b44a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-old-royal-naval-college-01-pcag39pdlyzac2ylh6xzcopm0nnlytssgzufkhebhs.jpg\" title=\"Old Royal Naval College, Royal Borough of Greenwich\" alt=\"Old Royal Naval College, Royal Borough of Greenwich\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-640d604 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"640d604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Old Royal Naval College<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0b10d0e\" data-id=\"0b10d0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10f972f elementor-widget elementor-widget-heading\" data-id=\"10f972f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About Old Royal Naval College<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1c165f elementor-widget elementor-widget-global elementor-global-17674 elementor-widget-text-editor\" data-id=\"e1c165f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Old Royal Naval College is Sir Christopher Wren&#8217;s riverside masterpiece, built in the 17th Century as the Royal Hospital for Seamen on the site of the Tudor Palace of Placentia. The Old Royal Naval College boasts beautiful surroundings &amp; some of the most magnificent interiors in London. The Painted Hall in King William Court is home to the largest painted ceiling in Europe, a Baroque masterpiece by Sir James Thornhill depicting over 300 years of English aristocracy &amp; British Naval Power. The Chapel of St Peter &amp; St Paul in Queen Mary Court has a beautiful interior designed by James &#8216;Athenian&#8217; Stewart. Visitors to the Old Royal Naval College can enjoy tours of the Painted Hall &amp; the grounds &amp; visit the cafe &amp; gift shop located in King William Court.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63f7972 elementor-widget elementor-widget-spacer\" data-id=\"63f7972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18d6873 elementor-widget elementor-widget-heading\" data-id=\"18d6873\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">What's On This Easter<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cca0381 elementor-widget elementor-widget-text-editor\" data-id=\"cca0381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>This Easter the Old Royal Naval College will be arranging an Easter Egg Trail through their iconic grounds between the 10th &#8211; 13th April. In addition to the Easter Egg Trail the artist Nick Ellwood is hosting an exhibition of hand drawings telling the story of characters from the Old Royal Naval College&#8217;s 500 year past.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p>Trinity Laban Conservatoire of Music &amp; Dance will also be performing Haydn&#8217;s\u00a0<em>The Creation<\/em> on the 8th April.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b2cb2e elementor-widget elementor-widget-spacer\" data-id=\"2b2cb2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcc3847 elementor-widget elementor-widget-heading\" data-id=\"fcc3847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Easter Events<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ed4c1c elementor-widget elementor-widget-text-editor\" data-id=\"6ed4c1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Easter Egg Trail |<\/strong> 10th April 2020 &#8211; 13th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Nick Ellwood Exhibition |<\/strong> 4th April 2020 &#8211; 31st May 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/>\u00a0<strong>Hadyn&#8217;s <em>The Creation<\/em> by Trinity Laban |<\/strong>\u00a08th April 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5802819 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5802819\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4e51b54\" data-id=\"4e51b54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8594292 elementor-widget elementor-widget-text-editor\" data-id=\"8594292\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/> \u00a0<a href=\"https:\/\/goo.gl\/maps\/T1pm3YZh97h4PMqF7\" target=\"_blank\" rel=\"nofollow noopener\">2 Min \/ 0.1 Miles from Greenwich Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/ornc.org\/easter-egg-trail\/\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit Old Royal Naval College Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c22b590 elementor-widget elementor-widget-spacer\" data-id=\"c22b590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd6743 elementor-widget elementor-widget-menu-anchor\" data-id=\"6fd6743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"thebritishmuseum\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-883ca90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"883ca90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e374ac5\" data-id=\"e374ac5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c1ad0c elementor-widget elementor-widget-heading\" data-id=\"0c1ad0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Rediscover the British Museums Collections Through Technology<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abaeca8 elementor-widget elementor-widget-heading\" data-id=\"abaeca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> The British Museum<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eeda53d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eeda53d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bf7fec2\" data-id=\"bf7fec2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc5cd53 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"cc5cd53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/the-british-museum-01-pcafpz9izasc6k9k2y4vljfznj5s4w1ez7saan3pgw.jpg\" title=\"The British Museum, Bloomsbury\" alt=\"The British Museum, Bloomsbury\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-122b0cc elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"122b0cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The British Museum<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8370e8b elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"8370e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/the-british-museum-01-pcafpz9izasc6k9k2y4vljfznj5s4w1ez7saan3pgw.jpg\" title=\"The British Museum, Bloomsbury\" alt=\"The British Museum, Bloomsbury\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c26d1ea elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"c26d1ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The British Museum<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-afe931d\" data-id=\"afe931d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61678e1 elementor-widget elementor-widget-heading\" data-id=\"61678e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About The British Museum<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc8913c elementor-widget elementor-widget-global elementor-global-81614 elementor-widget-text-editor\" data-id=\"bc8913c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The British Museum was created by an act of Parliament in 1753 &amp; opened to the public in 1759. The museum combined the collections of Sir Hans Sloane with the Cotton, Harley &amp; Royal Libraries creating a vast collection of historic &amp; scientific objects. The museum is housed in a collection of buildings entered through a magnificent Greek revival building designed by Sir Robert Smirke. Today The British Museum is free to visit &amp; is home to more than 60 free galleries where you can enjoy tours, talks &amp; family activities. You&#8217;ll also find a range of shops &amp; five restaurants at the museum.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55861df elementor-widget elementor-widget-spacer\" data-id=\"55861df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e376751 elementor-widget elementor-widget-heading\" data-id=\"e376751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">What's On This Easter<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c870b7 elementor-widget elementor-widget-text-editor\" data-id=\"4c870b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Families can learn about Roman Britain &amp; Emperor Claudius through museum objects before building their own wall in Minecraft.\u00a0<em>Colour the Collection<\/em> allows families to redesign the colour schemes of the museums most famous objects, many of them were brightly coloured to begin with.\u00a0<em>Egyptian Photo Booth<\/em> uses technology to turn visitors into Egyptian characters including Pharaohs &amp; Gods.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14282e1 elementor-widget elementor-widget-spacer\" data-id=\"14282e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2288a02 elementor-widget elementor-widget-heading\" data-id=\"2288a02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Easter Events<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a875f74 elementor-widget elementor-widget-text-editor\" data-id=\"a875f74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" alt=\"Date\" width=\"18\" \/> <strong>Colour the Collection (Age: 5+) |<\/strong> 11th April 2020, 11:00-16:00<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" alt=\"Date\" width=\"18\" \/> <strong>Build Roman Britain in Minecraft (Age: 7+) |<\/strong> 12th April 2020, 11:00-16:00<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" alt=\"Date\" width=\"18\" \/> <strong>Make a Manga Comic (Age: 7+) |<\/strong> 18th April 2020, 11:00-16:00<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" alt=\"Date\" width=\"18\" \/> <strong>Egyptian Photo Booth (Age: 5+) |<\/strong> 19th April 2020, 11:00-16:00<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" alt=\"Date\" width=\"18\" \/> <strong>Digital Little Feet (Age: Under 5) |<\/strong> 25th April 2020, 11:00-16:00<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" alt=\"Date\" width=\"18\" \/> <strong>Explore Egyptian Mummies (Age: 5+) |<\/strong> 26th April 2020, 11:00-16:00<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-37e3f8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37e3f8e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6484392\" data-id=\"6484392\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46cac42 elementor-widget elementor-widget-text-editor\" data-id=\"46cac42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/> \u00a0<a href=\"https:\/\/goo.gl\/maps\/dBxyykELARsWxM4aA\" target=\"_blank\" rel=\"nofollow noopener\">23 Min \/ 1 Mile from Embankment Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.britishmuseum.org\/exhibitions-events\/family\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit The British Museum Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-84e3517 elementor-widget elementor-widget-spacer\" data-id=\"84e3517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-595cb2a elementor-widget elementor-widget-menu-anchor\" data-id=\"595cb2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"cuttysark\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6bee8e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bee8e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c30d4f6\" data-id=\"c30d4f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11a1457 elementor-widget elementor-widget-heading\" data-id=\"11a1457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hunt for Eggs at the Old Royal Naval College<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3a0346 elementor-widget elementor-widget-heading\" data-id=\"e3a0346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> Cutty Sark<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c5453a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5453a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e2a7c38\" data-id=\"e2a7c38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86dc514 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"86dc514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/royal-greenwich-cutty-sark-02-pcfh58xywzlo0t8e24i4xeaqbjd8k8q29zugi34ipc.jpg\" title=\"Cutty Sark, Royal Borough of Greenwich | Viscount Cruises\" alt=\"Cutty Sark, Royal Borough of Greenwich | Viscount Cruises\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9d723b elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"b9d723b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cutty Sark<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-837fa57 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"837fa57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/royal-greenwich-cutty-sark-02-pcfh58xywzlo0t8e24i4xeaqbjd8k8q29zugi34ipc.jpg\" title=\"Cutty Sark, Royal Borough of Greenwich | Viscount Cruises\" alt=\"Cutty Sark, Royal Borough of Greenwich | Viscount Cruises\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f34a499 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"f34a499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cutty Sark<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2a6f34b\" data-id=\"2a6f34b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c0cbcc elementor-widget elementor-widget-heading\" data-id=\"8c0cbcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About Cutty Sark<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ad288 elementor-widget elementor-widget-global elementor-global-17656 elementor-widget-text-editor\" data-id=\"d6ad288\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Visit the last remaining tea clipper, Cutty Sark. Originally built at Dumbarton, Scotland in 1869 she spent her working life transporting cargo including tea from China and wool from Australia. She has now been fully restored and is an award winning visitor attraction.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1a85bd elementor-widget elementor-widget-spacer\" data-id=\"b1a85bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6f7bd7 elementor-widget elementor-widget-heading\" data-id=\"a6f7bd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">What's On This Easter<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-226910b elementor-widget elementor-widget-text-editor\" data-id=\"226910b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cutty Sark have a wide range of family activities lined up for Easter 2020. Sea SIGNS will involve craft activities, storytelling &amp; the opportunity to meet characters from Cutty Sark&#8217;s historic past.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p>Fly The Flag is a family workshop teaching the use of Signal Flags on ships.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p>Fantastic Flowers celebrates Cutty Sark&#8217;s visits to Wales with daffodil making workships.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p>Dashing Dragons is an artist-led dragon making workshop inspired by Cutty Sark&#8217;s journeys to China &amp; Wales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f1ef3d elementor-widget elementor-widget-spacer\" data-id=\"4f1ef3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3f85aa elementor-widget elementor-widget-heading\" data-id=\"a3f85aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Easter Events<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1af738e elementor-widget elementor-widget-text-editor\" data-id=\"1af738e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Sea SIGNS |<\/strong> 6th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Fly The Flag |<\/strong> 7th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Fantastic Flowers |<\/strong> 4th April 2020 &#8211; 11th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/>\u00a0<strong>Dashing Dragons\u00a0|<\/strong> 16th April 2020 &#8211; 18th April 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-84028e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84028e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-97f22f5\" data-id=\"97f22f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a20309 elementor-widget elementor-widget-text-editor\" data-id=\"1a20309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/> \u00a0<a href=\"https:\/\/g.page\/CuttySarkGreenwich?share\" target=\"_blank\" rel=\"nofollow noopener\">1 Min \/ 358 Feet from Greenwich Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.rmg.co.uk\/see-do\/exhibitions-events\/easter-board-cutty-sark\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit Cutty Sark Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-652c4ee elementor-widget elementor-widget-spacer\" data-id=\"652c4ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a5d5eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a5d5eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-507da5f\" data-id=\"507da5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fd1ce8 elementor-widget elementor-widget-heading\" data-id=\"9fd1ce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Southbank Centre<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb615a elementor-widget elementor-widget-heading\" data-id=\"1cb615a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> Southbank Centre<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b79b67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b79b67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e30c18f\" data-id=\"e30c18f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a2f3ba elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"1a2f3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/royal-festival-hall-01-np2c7gwhvac6h29rmoudak4txuwjbwhpgegwcn2sa8.jpg\" title=\"Royal Festival Hall, Southbank Centre\" alt=\"Royal Festival Hall, Southbank Centre\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-874584f elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"874584f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Southbank Centre<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a086d87 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"a086d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/royal-festival-hall-01-np2c7gwhvac6h29rmoudak4txuwjbwhpgegwcn2sa8.jpg\" title=\"Royal Festival Hall, Southbank Centre\" alt=\"Royal Festival Hall, Southbank Centre\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9723b56 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"9723b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Southbank Centre<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7666288\" data-id=\"7666288\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-423b5b4 elementor-widget elementor-widget-heading\" data-id=\"423b5b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About Southbank Centre<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33b886b elementor-widget elementor-widget-text-editor\" data-id=\"33b886b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Southbank Centre is home to Royal Festival Hall &amp; The National Theatre &amp; they operate a wide range of indoor &amp; outdoor events throughout the year.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8099afa elementor-widget elementor-widget-spacer\" data-id=\"8099afa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e108e8f elementor-widget elementor-widget-heading\" data-id=\"e108e8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Easter Events<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adf9213 elementor-widget elementor-widget-text-editor\" data-id=\"adf9213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Plant Pots in Paper Bags (Age: 5+) |<\/strong> 4th April 2020 &#8211; 17th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Family Tree Trail |<\/strong> 4th April 2020 &#8211; 19th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Soundpit (All Ages) |<\/strong> 4th April 2020 &#8211; 19th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/>\u00a0<strong>Family Folk Club |<\/strong> 9th April 2020, 13:00 &amp; 11th April 2020, 13:00<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/>\u00a0<strong>Tiddler and Other Terrific Tales (All Ages) |<\/strong> 4th April 2020 &#8211; 11th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Craft an Eco Mobile |<\/strong> 9th April 2020 &#8211; 16th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Clay Time (Age: 5+) |<\/strong> 10th April 2020 &#8211; 15th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Build A Jam Jar Lantern |<\/strong> 11th April 2020 &#8211; 14th April 2020<\/p><p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> <strong>Pedal Power Disco<\/strong> | 13th April 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c135090 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c135090\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5c21f9d\" data-id=\"5c21f9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a531567 elementor-widget elementor-widget-text-editor\" data-id=\"a531567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/> \u00a0<a href=\"https:\/\/goo.gl\/maps\/PJ4Zxvb7GiHGfP3T7\" target=\"_blank\" rel=\"nofollow noopener\">1 Min \/ 302 Feet from Festival Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.southbankcentre.co.uk\/whats-on\/festivals-series\/easter\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit Southbank Centre Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-de972d0 elementor-widget elementor-widget-spacer\" data-id=\"de972d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6e2d4c elementor-widget elementor-widget-menu-anchor\" data-id=\"d6e2d4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"rivercruises\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c782578 elementor-widget elementor-widget-heading\" data-id=\"c782578\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">River Cruises<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d65bfab elementor-widget elementor-widget-menu-anchor\" data-id=\"d65bfab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"thamesbarriercruise\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d5e123d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d5e123d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-60ddeb3\" data-id=\"60ddeb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-485057f elementor-widget elementor-widget-heading\" data-id=\"485057f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cruise Through the Thames Barrier<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c6434d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c6434d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e5e629\" data-id=\"4e5e629\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa083bf elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"aa083bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-07-thames-barrier-cruises-2020-thames-barrier-01-pcag2hi7wxwons3k1ur69vts73iljwoud49v66k4og.jpg\" title=\"Thames Barrier\" alt=\"Thames Barrier\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1ae61 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"2b1ae61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-07-thames-barrier-cruises-2020-thames-barrier-02-pcag1uy3cx1sx50bpl04m1ipxulsf67aa0m7njhkts.jpg\" title=\"Thames Barrier\" alt=\"Thames Barrier\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daba7d9 elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"daba7d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Top: The Thames Barrier | Bottom: Delta Span in the maintenence position.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fb7a13 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"7fb7a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-07-thames-barrier-cruises-2020-thames-barrier-01-pcag2hi7wxwons3k1ur69vts73iljwoud49v66k4og.jpg\" title=\"Thames Barrier\" alt=\"Thames Barrier\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d99bd17 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"d99bd17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-07-thames-barrier-cruises-2020-thames-barrier-02-pcag1uy3cx1sx50bpl04m1ipxulsf67aa0m7njhkts.jpg\" title=\"Thames Barrier\" alt=\"Thames Barrier\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-821ac04 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"821ac04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Top: The Thames Barrier | Bottom: Delta Span in the maintenence position.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c091487\" data-id=\"c091487\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92ad09a elementor-widget elementor-widget-heading\" data-id=\"92ad09a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About The Thames Barrier<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb69c5e elementor-widget elementor-widget-global elementor-global-17689 elementor-widget-text-editor\" data-id=\"eb69c5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Thames Flood Barrier is one of the largest movable flood defences in the world. Since its completion in 1986 the barrier has been closed 182 times (accurate as of February 2018). 95 of these closures were to protect against tidal flooding &amp; 87 closures were to protect against tidal\/fluvial flooding.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2e96e8 elementor-widget elementor-widget-spacer\" data-id=\"b2e96e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cc635d elementor-widget elementor-widget-heading\" data-id=\"2cc635d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Thames Barrier Cruises<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d7acda elementor-widget elementor-widget-text-editor\" data-id=\"0d7acda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our Thames Barrier Cruises depart five times each day from Westminster Pier calling at St. Katharine Pier &amp; Greenwich Pier before cruising through the barrier. These river trips are a unique opportunity to see the Thames Barrier up close &amp; learn more about its role protecting over 125 kilometres of London from flooding.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b93c9c1 elementor-widget elementor-widget-spacer\" data-id=\"b93c9c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66955bf elementor-widget elementor-widget-heading\" data-id=\"66955bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Departures<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da741c6 elementor-widget elementor-widget-text-editor\" data-id=\"da741c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> Daily Departures &#8211; 30th March 2020 &#8211; 1st November 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-46aca9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46aca9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1a4a55d\" data-id=\"1a4a55d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d0473a elementor-widget elementor-widget-text-editor\" data-id=\"8d0473a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Walking Distance\" width=\"10\" \/> \u00a0Departures from Westminster Pier, St. Katharine Pier &amp; Greenwich Pier<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.viscountcruises.com\/news\/2020\/03\/07\/thames-barrier-cruises-2020\/\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Read More about our Thames Barrier Cruises<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf8ac69 elementor-widget elementor-widget-spacer\" data-id=\"bf8ac69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49aca2d elementor-widget elementor-widget-menu-anchor\" data-id=\"49aca2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"artexhibitions\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4350ebd elementor-widget elementor-widget-heading\" data-id=\"4350ebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Art &amp; Exhibitions<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20bb37c elementor-widget elementor-widget-menu-anchor\" data-id=\"20bb37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"britishbaroquepowerandillusion\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66feb71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66feb71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b850890\" data-id=\"b850890\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6d2261 elementor-widget elementor-widget-heading\" data-id=\"d6d2261\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tudors To Windsors: British Royal Portraits &amp; Faces of a Queen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d802336 elementor-widget elementor-widget-heading\" data-id=\"d802336\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> The Queen's House<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-927d90c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"927d90c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4016607\" data-id=\"4016607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f125b1 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"5f125b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/the-queens-house-01-pcaiobq67id7qbsi3f0c77cf5wzs03859kwxynf7hs.jpg\" title=\"The Queens House, Royal Borough of Greenwich\" alt=\"aThe Queens House, Royal Borough of Greenwich\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-523dfc6 elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"523dfc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Queen&#8217;s House<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14b962f elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"14b962f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/the-queens-house-01-pcaiobq67id7qbsi3f0c77cf5wzs03859kwxynf7hs.jpg\" title=\"The Queens House, Royal Borough of Greenwich\" alt=\"aThe Queens House, Royal Borough of Greenwich\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d379c3e elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"d379c3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Queen&#8217;s House<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-afb0249\" data-id=\"afb0249\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01df445 elementor-widget elementor-widget-heading\" data-id=\"01df445\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About The Queen's House<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aea76cf elementor-widget elementor-widget-global elementor-global-17677 elementor-widget-text-editor\" data-id=\"aea76cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tThe Queens House was the first classical building in England, built by Inigo Jones for Queen Anne of Denmark, wife of King James I. Now over 400 years old the house has been extensively refurbished and is home to an internationally renowned art collection.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d37dce elementor-widget elementor-widget-spacer\" data-id=\"5d37dce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4cf85b elementor-widget elementor-widget-heading\" data-id=\"c4cf85b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About the Exhibition<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-302d614 elementor-widget elementor-widget-text-editor\" data-id=\"302d614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Portraits have been used for centuries to showcase the monarchy in all its grandeur &amp; splendour. Tudor To Windsors: British Royal Portraits is a landmark exhibition curated by Royal Museums Greenwich which brings paintings from their own collection together with paintings from the National Portrait Gallery &amp; private collections. The exhibition will explore how royal portraiture has changed &amp; includes works from famous painters such as Sir Peter Lely &amp; more modern artists such as royal photographer Cecil Beaton.<\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p>In addition to Tudors To Windsors, Faces of a Queen is another exhibition which brings together the three Armada Portraits of Elizabeth I for the first time in their 430 year history. Visitors can compare the similarities &amp; differences between the three paintings from Royal Museums Greenwich, Woburn Abbey &amp; the National Portrait Gallery. Like many Tudor paintings the armada portraits are full of hidden meaning &amp; metaphor which when combined portray Elizabeth I as the iconic figurehead we see today.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0a3387 elementor-widget elementor-widget-spacer\" data-id=\"c0a3387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-826a295 elementor-widget elementor-widget-heading\" data-id=\"826a295\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Exhibition Dates<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5e62ce elementor-widget elementor-widget-text-editor\" data-id=\"b5e62ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> 3rd April 2020 &#8211; 31st August 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c3635d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c3635d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bcde2cc\" data-id=\"bcde2cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69fc07d elementor-widget elementor-widget-text-editor\" data-id=\"69fc07d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/> \u00a0<a href=\"https:\/\/g.page\/QueensHouseGreenwich?share\" target=\"_blank\" rel=\"nofollow noopener\">8 Min \/ 0.4 Miles from Greenwich Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.rmg.co.uk\/whats-on\/tudors-to-windsors\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit Royal Museums Greenwich Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-884e5db elementor-widget elementor-widget-spacer\" data-id=\"884e5db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c07aa3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c07aa3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-37a7ddc\" data-id=\"37a7ddc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9e8ea7 elementor-widget elementor-widget-heading\" data-id=\"c9e8ea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">British Baroque: Power and Illusion<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-725e511 elementor-widget elementor-widget-heading\" data-id=\"725e511\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> Tate Britain<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec2822 elementor-widget elementor-widget-heading\" data-id=\"4ec2822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About Tate Britain<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b9239b elementor-widget elementor-widget-global elementor-global-47023 elementor-widget-text-editor\" data-id=\"8b9239b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In 1889 the sugar merchant Henry Tate offered the government his collection of 65 British paintings to be displayed to the public. Due to a lack of space for British art at the National Gallery Tate provided \u00a380,000 to build the National Gallery of British Art. The new gallery was designed by the architect Sidney R. J. Smith &amp; built on the site of the old Millbank penitentiary. The gallery opened in 1897 with 245 works of art in eight galleries &amp; quickly became known as the Tate Gallery. The gallery officially became known as the Tate Gallery in 1932 &amp; then the Tate Britain in 2000 after the opening of the Tate Modern inside the old Bankside power station. The Tate Britain displays over 700 artworks, is free to visit &amp; also has the Djanogly Caf\u00e9, Rex Whistler Restaurant &amp; a wide range of exhibitions &amp; events take place throughout the year <sub>(some exhibitions charge an entry fee)<\/sub>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba0255 elementor-widget elementor-widget-spacer\" data-id=\"3ba0255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8245804 elementor-widget elementor-widget-heading\" data-id=\"8245804\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About the Exhibition<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba27ad0 elementor-widget elementor-widget-text-editor\" data-id=\"ba27ad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>British Baroque: Power and Illusion is the first exhibition by Tate to explore Baroque art in Britain. Baroque was popular during the 17th century &amp; notable examples in London include the ceiling of The Banqueting House, painted by Peter Paul Rubens for Charles I &amp; the Painted Hall at the Royal Hospital For Seamen <sub>(now the Old Royal Naval College)<\/sub>, painted by James Thornhill. The exhibition displays works by a number of leading artists including James Thornhill, Gofrey Kneller &amp; Peter Lely.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c810684 elementor-widget elementor-widget-spacer\" data-id=\"c810684\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eeebab elementor-widget elementor-widget-heading\" data-id=\"4eeebab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Exhibition Dates<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6261044 elementor-widget elementor-widget-text-editor\" data-id=\"6261044\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/> 4th February 2020 &#8211; 19th April 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d8aa327 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8aa327\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c222bde\" data-id=\"c222bde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c77607b elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"c77607b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-british-baroque-power-illusion-01-pcag3pomu5l5tgbdvvun12og47gulok876xoq6qmk0.jpg\" title=\"Old Royal Naval College, The Painted Hall The West Wall \u2013 George I, His Family and His Virtues\" alt=\"Old Royal Naval College, The Painted Hall The West Wall - George I, His Family and His Virtues\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3123b54 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"3123b54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/the-banqueting-house-06.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-221c5a4 elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"221c5a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Examples of Baroque Art<\/em>: Top: The West Wall, Painted Hall, Old Royal Naval College | Bottom: The Apotheosis of James I, The Banqueting House<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1573d1e elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"1573d1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-british-baroque-power-illusion-01-pcag3pomu5l5tgbdvvun12og47gulok876xoq6qmk0.jpg\" title=\"Old Royal Naval College, The Painted Hall The West Wall \u2013 George I, His Family and His Virtues\" alt=\"Old Royal Naval College, The Painted Hall The West Wall - George I, His Family and His Virtues\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a48794 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"8a48794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/the-banqueting-house-06.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b05bb10 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"b05bb10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Examples of Baroque Art<\/em>: Top: The West Wall, Painted Hall, Old Royal Naval College | Bottom: The Apotheosis of James I, The Banqueting House<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-89230e5\" data-id=\"89230e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-94a52fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94a52fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-94c71f1\" data-id=\"94c71f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73eb22e elementor-widget elementor-widget-text-editor\" data-id=\"73eb22e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/DQrG6UEjcST1528T7\" target=\"_blank\" rel=\"nofollow noopener\">18 Min \/ 0.9 Miles from Westminster Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.tate.org.uk\/whats-on\/tate-britain\/exhibition\/british-baroque\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit Tate Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f2ae19 elementor-widget elementor-widget-spacer\" data-id=\"4f2ae19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b57add9 elementor-widget elementor-widget-menu-anchor\" data-id=\"b57add9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"georgeivartspectacle\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e21809c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e21809c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cad6277\" data-id=\"cad6277\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e14095 elementor-widget elementor-widget-heading\" data-id=\"0e14095\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">George IV: Art &amp; Spectacle<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d5a295 elementor-widget elementor-widget-heading\" data-id=\"6d5a295\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-map.svg\" alt=\"Viscount Cruises\" width=\"10\" \/> Buckingham Palace: The Queens Gallery<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4da12c3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4da12c3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b254166\" data-id=\"b254166\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70d60e7c elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"70d60e7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-george-iv-art-spectacle-01-omwnosirsrz593wka9hnxpsbmo3kdb3fecunwh1ewg.jpg\" title=\"George IV: Art &amp; Spectacle at The Queens Gallery, Buckingham Palace\" alt=\"George IV: Art &amp; Spectacle at The Queens Gallery, Buckingham Palace\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-618b2c90 elementor-hidden-phone elementor-widget elementor-widget-text-editor\" data-id=\"618b2c90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Coronation portrait of George IV, by Sir Thomas Lawrence, 1821<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14eb9883 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"14eb9883\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/elementor\/thumbs\/2020-03-20-easter-holidays-2020-george-iv-art-spectacle-01-omwnosirsrz593wka9hnxpsbmo3kdb3fecunwh1ewg.jpg\" title=\"George IV: Art &amp; Spectacle at The Queens Gallery, Buckingham Palace\" alt=\"George IV: Art &amp; Spectacle at The Queens Gallery, Buckingham Palace\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70e835d6 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"70e835d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Coronation portrait of George IV, by Sir Thomas Lawrence, 1821<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8411150\" data-id=\"8411150\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-854ee6f elementor-widget elementor-widget-heading\" data-id=\"854ee6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About The Queens Gallery<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-626a580 elementor-widget elementor-widget-text-editor\" data-id=\"626a580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Queens Gallery at Buckingham Palace displays regular exhibitions of items from the Royal Collection. Families can explore the exhibitions with family activity bags &amp; visit the family activity room.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f1d250 elementor-widget elementor-widget-spacer\" data-id=\"8f1d250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a954cb elementor-widget elementor-widget-heading\" data-id=\"2a954cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">About the Exhibition<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c275e56 elementor-widget elementor-widget-text-editor\" data-id=\"4c275e56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>George IV had the shortest reign of the Georgian Kings, just 10 years (1820-1830). At the time of his accession in 1820 he had already ruled for 9 years during his fathers illness, a period known as the Regency. George is often remembered as an excessive drinker who spent vast sums of money &amp; accumulated enormous debt during a time of great austerity. He is also remembered for his poor relationship with his with, Queen Caroline of Brunswick. Despite these faults George had excellent taste in the arts &amp; allowed the change to a constitutional government.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1f6ebf elementor-widget elementor-widget-spacer\" data-id=\"a1f6ebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-110b8e8d elementor-widget elementor-widget-text-editor\" data-id=\"110b8e8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>During George&#8217;s time as Prince of Wales he amassed such vast collections of art including Dutch &amp; Flemish masters, porcelain, intricate goldsmiths work, books, prints &amp; weapons that he could barely fit all of the items in his London home at Carlton House. After George&#8217;s accession he set about transforming Buckingham Palace &amp; Windsor Castle to house his prized collections &amp; he also built the magnificent Brighton Pavilion. George IV: Art &amp; Spectacle is a special exhibition curated by Royal Collection Trust which brings together items created by the finest artists &amp; craftsmen to tell the story of one of our most magnificent kings.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b31b5df elementor-widget elementor-widget-spacer\" data-id=\"2b31b5df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb5601 elementor-widget elementor-widget-heading\" data-id=\"5bb5601\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Exhibition Dates<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcde5ec elementor-widget elementor-widget-text-editor\" data-id=\"fcde5ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-calendar.svg\" width=\"18\" \/>\u00a015th November 2019 &#8211; 3rd May 2020<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66f9334c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66f9334c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2c4cef74\" data-id=\"2c4cef74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fd6cf71 elementor-widget elementor-widget-text-editor\" data-id=\"4fd6cf71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" src=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/images\/pictograms\/bullet-walking-blue.svg\" alt=\"Walking Distance\" width=\"14\" \/>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/idFw4biMJdLUbbeq8\" target=\"_blank\" rel=\"nofollow noopener\">18 Min \/ 0.9 Miles from Westminster Pier<\/a><\/p><p>\t\t<div data-elementor-type=\"widget\" data-elementor-id=\"25661\" class=\"elementor elementor-25661 elementor-bc-flex-widget\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25661 elementor-widget elementor-widget-spacer\" data-id=\"25661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><p><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/www.rct.uk\/whatson\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Visit Royal Collection Trust Website<\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e16cf50 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"7e16cf50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdacd97 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"cdacd97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70c9bc99 elementor-hidden-phone elementor-widget elementor-widget-breadcrumbs\" data-id=\"70c9bc99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.viscountcruises.com\/\">Viscount Cruises<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-831ca41 elementor-widget elementor-widget-html\" data-id=\"831ca41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">\r\n    {\r\n      \"@context\": \"https:\/\/schema.org\",\r\n      \"@type\": \"NewsArticle\",\r\n      \"mainEntityOfPage\": {\r\n        \"@type\": \"WebPage\",\r\n        \"@id\": \"https:\/\/www.viscountcruises.com\/news\/2020\/03\/20\/easter-holidays-2020\/\"\r\n      },\r\n      \"headline\": \"Easter Holidays 2020\",\r\n      \"image\": [\r\n        \"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/page-news-2020-03-20-easter-holidays-2020.jpg\"\r\n       ],\r\n      \"datePublished\": \"2020-03-20T08:00:00+08:00\",\r\n      \"dateModified\": \"2020-04-11T08:00:00+08:00\",\r\n      \"author\": {\r\n        \"@type\": \"Person\",\r\n        \"name\": \"Viscount Cruises\"\r\n      },\r\n       \"publisher\": {\r\n        \"@type\": \"Organization\",\r\n        \"name\": \"Viscount Cruises\",\r\n        \"logo\": {\r\n          \"@type\": \"ImageObject\",\r\n          \"url\": \"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/2018\/12\/viscount-cruises-logo-300-36.png\"\r\n        }\r\n      },\r\n      \"description\": \"Easter is a great time to explore London & there is a wide range of family activities & events taking place at different attractions across the city.\"\r\n    }\r\n    <\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-556e704a\" data-id=\"556e704a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d8b9723 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"5d8b9723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0104d88 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0104d88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ec34a85\" data-id=\"ec34a85\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49e4e74 elementor-widget elementor-widget-heading\" data-id=\"49e4e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Categories<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e94af75 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e94af75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#top\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-up\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8 256C8 119 119 8 256 8s248 111 248 248-111 248-248 248S8 393 8 256zm292 116V256h70.9c10.7 0 16.1-13 8.5-20.5L264.5 121.2c-4.7-4.7-12.2-4.7-16.9 0l-115 114.3c-7.6 7.6-2.2 20.5 8.5 20.5H212v116c0 6.6 5.4 12 12 12h64c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Back to Top<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#familyactivities\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Family Activities<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#rivercruises\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>River Cruises<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#artexhibitions\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Art &amp; Exhibitions<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-08f6258 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"08f6258\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d349c99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d349c99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-18a36d8b\" data-id=\"18a36d8b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a72672e elementor-widget elementor-widget-heading\" data-id=\"a72672e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.viscountcruises.com\/news-offers\/\">News &amp; Offers<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1276d3bf elementor-widget elementor-widget-text-editor\" data-id=\"1276d3bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>View our latest news &amp; special offers.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4de7501 elementor-widget elementor-widget-spacer\" data-id=\"4de7501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-733fd1e7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"733fd1e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.viscountcruises.com\/news-offers\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">News &amp; Offers<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-87af820 elementor-widget elementor-widget-spacer\" data-id=\"87af820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bff92f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bff92f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8d42783\" data-id=\"8d42783\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-529584c elementor-widget elementor-widget-heading\" data-id=\"529584c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">News Tags<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3e3a6f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-global elementor-global-80647 elementor-widget-icon-list\" data-id=\"f3e3a6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>All News<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/bankside-pier\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Bankside Pier<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/embankment-pier\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Embankment Pier<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/festival-pier\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Festival Pier<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/greenwich-pier\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Greenwich Pier<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/public-holidays\/\" target=\"_blank\" rel=\"nofollow\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Public Holidays, Festivals &amp; Events<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/new-years-eve\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>New Year's Eve<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/private-charters\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Private Charters<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/sightseeing\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Sightseeing<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/special-offers\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Special Offers<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/tower-bridge-quay\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Tower Bridge Quay<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/thames-sunday-evening-cruise\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Sunday Evening Cruise<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/thames-barrier\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Thames Barrier<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/thames-river-sightseeing\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Thames River Sightseeing<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.viscountcruises.com\/news\/tag\/westminster-millennium-pier\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tag\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 252.118V48C0 21.49 21.49 0 48 0h204.118a48 48 0 0 1 33.941 14.059l211.882 211.882c18.745 18.745 18.745 49.137 0 67.882L293.823 497.941c-18.745 18.745-49.137 18.745-67.882 0L14.059 286.059A48 48 0 0 1 0 252.118zM112 64c-26.51 0-48 21.49-48 48s21.49 48 48 48 48-21.49 48-48-21.49-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Westminster Millennium Pier<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d416d17 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"5d416d17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1eb44a5f elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-spacer\" data-id=\"1eb44a5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-231de7cf elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-breadcrumbs\" data-id=\"231de7cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.viscountcruises.com\/\">Viscount Cruises<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d4fba8b elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"3d4fba8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e690f03 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e690f03\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f6ad4aa\" data-id=\"f6ad4aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5722ec8 elementor-widget elementor-widget-text-editor\" data-id=\"5722ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Include: 4th April 2020- 19th April 2020<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Easter is a great time to explore London &#038; there is a wide range of family activities &#038; events taking place at different attractions across the city.<\/p>","protected":false},"author":242,"featured_media":81666,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[184,217,156,305,148,264,149,186,181],"tags":[185,218,157,306,150,266,151,187,180],"class_list":["post-80384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-embankment-pier","category-festival-pier","category-greenwich-pier","category-public-holidays","category-sightseeing","category-thames-barrier","category-thames-river-sightseeing","category-tower-bridge-quay","category-westminster-millennium-pier","tag-embankment-pier","tag-festival-pier","tag-greenwich-pier","tag-public-holidays","tag-sightseeing","tag-thames-barrier","tag-thames-river-sightseeing","tag-tower-bridge-quay","tag-westminster-millennium-pier"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Easter Holidays on the River Thames with Viscount Cruises<\/title>\n<meta name=\"description\" content=\"Easter is a great time to explore London &amp; there is a wide range of family activities &amp; events taking place at different attractions across the city.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.viscountcruises.com\/de\/news\/2020\/03\/20\/easter-holidays-2020\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Easter Holidays on the River Thames with Viscount Cruises\" \/>\n<meta property=\"og:description\" content=\"Easter is a great time to explore London &amp; there is a wide range of family activities &amp; events taking place at different attractions across the city.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.viscountcruises.com\/de\/news\/2020\/03\/20\/easter-holidays-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Viscount Cruises\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Viscount-Cruises-869202513167565\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T23:20:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/page-news-2020-03-20-easter-holidays-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Viscount Cruises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@viscountcruises\" \/>\n<meta name=\"twitter:site\" content=\"@viscountcruises\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Viscount Cruises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"25\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/\"},\"author\":{\"name\":\"Viscount Cruises\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#\\\/schema\\\/person\\\/5e7465737a8bbfb5c985786037750f83\"},\"headline\":\"Easter Holidays 2020\",\"datePublished\":\"2020-03-20T08:00:00+00:00\",\"dateModified\":\"2021-04-27T23:20:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/\"},\"wordCount\":2282,\"publisher\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.viscountcruises.com\\\/wp-content\\\/uploads\\\/page-news-2020-03-20-easter-holidays-2020.jpg\",\"keywords\":[\"Embankment Pier\",\"Festival Pier\",\"Greenwich Pier\",\"Public Holidays, Festivals &amp; Events\",\"Sightseeing\",\"Thames Barrier\",\"Thames River Sightseeing\",\"Tower Bridge Quay\",\"Westminster Millennium Pier\"],\"articleSection\":[\"Embankment Pier\",\"Festival Pier\",\"Greenwich Pier\",\"Public Holidays, Festivals &amp; Events\",\"Sightseeing\",\"Thames Barrier\",\"Thames River Sightseeing\",\"Tower Bridge Quay\",\"Westminster Millennium Pier\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/\",\"url\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/\",\"name\":\"Easter Holidays on the River Thames with Viscount Cruises\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.viscountcruises.com\\\/wp-content\\\/uploads\\\/page-news-2020-03-20-easter-holidays-2020.jpg\",\"datePublished\":\"2020-03-20T08:00:00+00:00\",\"dateModified\":\"2021-04-27T23:20:04+00:00\",\"description\":\"Easter is a great time to explore London & there is a wide range of family activities & events taking place at different attractions across the city.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.viscountcruises.com\\\/wp-content\\\/uploads\\\/page-news-2020-03-20-easter-holidays-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/www.viscountcruises.com\\\/wp-content\\\/uploads\\\/page-news-2020-03-20-easter-holidays-2020.jpg\",\"width\":1800,\"height\":600,\"caption\":\"Easter Holidays 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/es\\\/news\\\/2020\\\/03\\\/20\\\/easter-holidays-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Viscount Cruises\",\"item\":\"https:\\\/\\\/www.viscountcruises.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Easter Holidays 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#website\",\"url\":\"https:\\\/\\\/www.viscountcruises.com\\\/\",\"name\":\"Viscount Cruises\",\"description\":\"Boats for Every Occasion.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.viscountcruises.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#organization\",\"name\":\"Viscount Cruises\",\"url\":\"https:\\\/\\\/www.viscountcruises.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.viscountcruises.com\\\/wp-content\\\/uploads\\\/Viscount-Cruises-Logo-Drop-Shadow-PNG-768-94.webp\",\"contentUrl\":\"https:\\\/\\\/www.viscountcruises.com\\\/wp-content\\\/uploads\\\/Viscount-Cruises-Logo-Drop-Shadow-PNG-768-94.webp\",\"width\":768,\"height\":94,\"caption\":\"Viscount Cruises\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Viscount-Cruises-869202513167565\\\/\",\"https:\\\/\\\/x.com\\\/viscountcruises\",\"https:\\\/\\\/www.instagram.com\\\/viscountcruises\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/viscount-cruises\",\"https:\\\/\\\/www.pinterest.com\\\/viscountcruises\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.viscountcruises.com\\\/#\\\/schema\\\/person\\\/5e7465737a8bbfb5c985786037750f83\",\"name\":\"Viscount Cruises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c41d990d8e8e84295eb1dd3e71cb567c98439776c392aacb8b8b746a33595d82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c41d990d8e8e84295eb1dd3e71cb567c98439776c392aacb8b8b746a33595d82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c41d990d8e8e84295eb1dd3e71cb567c98439776c392aacb8b8b746a33595d82?s=96&d=mm&r=g\",\"caption\":\"Viscount Cruises\"},\"sameAs\":[\"https:\\\/\\\/www.viscountcruises.com\"],\"url\":\"https:\\\/\\\/www.viscountcruises.com\\\/de\\\/news\\\/author\\\/viscount-cruises-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Easter Holidays on the River Thames with Viscount Cruises","description":"Easter is a great time to explore London & there is a wide range of family activities & events taking place at different attractions across the city.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.viscountcruises.com\/de\/news\/2020\/03\/20\/easter-holidays-2020\/","og_locale":"de_DE","og_type":"article","og_title":"Easter Holidays on the River Thames with Viscount Cruises","og_description":"Easter is a great time to explore London & there is a wide range of family activities & events taking place at different attractions across the city.","og_url":"https:\/\/www.viscountcruises.com\/de\/news\/2020\/03\/20\/easter-holidays-2020\/","og_site_name":"Viscount Cruises","article_publisher":"https:\/\/www.facebook.com\/Viscount-Cruises-869202513167565\/","article_published_time":"2020-03-20T08:00:00+00:00","article_modified_time":"2021-04-27T23:20:04+00:00","og_image":[{"width":1800,"height":600,"url":"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/page-news-2020-03-20-easter-holidays-2020.jpg","type":"image\/jpeg"}],"author":"Viscount Cruises","twitter_card":"summary_large_image","twitter_creator":"@viscountcruises","twitter_site":"@viscountcruises","twitter_misc":{"Verfasst von":"Viscount Cruises","Gesch\u00e4tzte Lesezeit":"25\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/#article","isPartOf":{"@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/"},"author":{"name":"Viscount Cruises","@id":"https:\/\/www.viscountcruises.com\/#\/schema\/person\/5e7465737a8bbfb5c985786037750f83"},"headline":"Easter Holidays 2020","datePublished":"2020-03-20T08:00:00+00:00","dateModified":"2021-04-27T23:20:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/"},"wordCount":2282,"publisher":{"@id":"https:\/\/www.viscountcruises.com\/#organization"},"image":{"@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/page-news-2020-03-20-easter-holidays-2020.jpg","keywords":["Embankment Pier","Festival Pier","Greenwich Pier","Public Holidays, Festivals &amp; Events","Sightseeing","Thames Barrier","Thames River Sightseeing","Tower Bridge Quay","Westminster Millennium Pier"],"articleSection":["Embankment Pier","Festival Pier","Greenwich Pier","Public Holidays, Festivals &amp; Events","Sightseeing","Thames Barrier","Thames River Sightseeing","Tower Bridge Quay","Westminster Millennium Pier"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/","url":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/","name":"Easter Holidays on the River Thames with Viscount Cruises","isPartOf":{"@id":"https:\/\/www.viscountcruises.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/page-news-2020-03-20-easter-holidays-2020.jpg","datePublished":"2020-03-20T08:00:00+00:00","dateModified":"2021-04-27T23:20:04+00:00","description":"Easter is a great time to explore London & there is a wide range of family activities & events taking place at different attractions across the city.","breadcrumb":{"@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/#primaryimage","url":"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/page-news-2020-03-20-easter-holidays-2020.jpg","contentUrl":"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/page-news-2020-03-20-easter-holidays-2020.jpg","width":1800,"height":600,"caption":"Easter Holidays 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.viscountcruises.com\/es\/news\/2020\/03\/20\/easter-holidays-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Viscount Cruises","item":"https:\/\/www.viscountcruises.com\/"},{"@type":"ListItem","position":2,"name":"Easter Holidays 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.viscountcruises.com\/#website","url":"https:\/\/www.viscountcruises.com\/","name":"Viscount Cruises","description":"\"Boote f\u00fcr jeden Anlass.\"","publisher":{"@id":"https:\/\/www.viscountcruises.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viscountcruises.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.viscountcruises.com\/#organization","name":"Viscount Cruises","url":"https:\/\/www.viscountcruises.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.viscountcruises.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/Viscount-Cruises-Logo-Drop-Shadow-PNG-768-94.webp","contentUrl":"https:\/\/www.viscountcruises.com\/wp-content\/uploads\/Viscount-Cruises-Logo-Drop-Shadow-PNG-768-94.webp","width":768,"height":94,"caption":"Viscount Cruises"},"image":{"@id":"https:\/\/www.viscountcruises.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Viscount-Cruises-869202513167565\/","https:\/\/x.com\/viscountcruises","https:\/\/www.instagram.com\/viscountcruises\/","https:\/\/www.linkedin.com\/company\/viscount-cruises","https:\/\/www.pinterest.com\/viscountcruises\/"]},{"@type":"Person","@id":"https:\/\/www.viscountcruises.com\/#\/schema\/person\/5e7465737a8bbfb5c985786037750f83","name":"Viscount Cruises","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c41d990d8e8e84295eb1dd3e71cb567c98439776c392aacb8b8b746a33595d82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c41d990d8e8e84295eb1dd3e71cb567c98439776c392aacb8b8b746a33595d82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c41d990d8e8e84295eb1dd3e71cb567c98439776c392aacb8b8b746a33595d82?s=96&d=mm&r=g","caption":"Viscount Cruises"},"sameAs":["https:\/\/www.viscountcruises.com"],"url":"https:\/\/www.viscountcruises.com\/de\/news\/author\/viscount-cruises-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/posts\/80384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/comments?post=80384"}],"version-history":[{"count":0,"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/posts\/80384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/media\/81666"}],"wp:attachment":[{"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/media?parent=80384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/categories?post=80384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viscountcruises.com\/de\/wp-json\/wp\/v2\/tags?post=80384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}